{"id":195,"count":3,"description":"","link":"https:\/\/18kenglish.com\/ja\/tag\/%e5%a3%ab%e6%9e%97%e8%8b%b1%e6%96%87\/","name":"\u58eb\u6797\u548c\u8a33","slug":"%e5%a3%ab%e6%9e%97%e8%8b%b1%e6%96%87","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/18kenglish.com\/ja\/wp-json\/wp\/v2\/tags\/195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/18kenglish.com\/ja\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/18kenglish.com\/ja\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/18kenglish.com\/ja\/wp-json\/wp\/v2\/posts?tags=195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}