{"id":756,"count":1,"description":"","link":"https:\/\/18kenglish.com\/ja\/tag\/%e8%8b%b1%e6%96%87%e4%bf%a1%e4%bb%b6%e6%a0%bc%e5%bc%8f\/","name":"\u548c\u6587\u4fe1\u4ef6\u683c\u5f0f","slug":"%e8%8b%b1%e6%96%87%e4%bf%a1%e4%bb%b6%e6%a0%bc%e5%bc%8f","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/18kenglish.com\/ja\/wp-json\/wp\/v2\/tags\/756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/18kenglish.com\/ja\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/18kenglish.com\/ja\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/18kenglish.com\/ja\/wp-json\/wp\/v2\/posts?tags=756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}