{"id":361,"count":10,"description":"","link":"https:\/\/18kenglish.com\/th\/tag\/\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e15\u0e49\u0e2b\u0e27\u0e31\u0e19\/","name":"\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e15\u0e49\u0e2b\u0e27\u0e31\u0e19","slug":"taiwan-tourism","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/18kenglish.com\/th\/wp-json\/wp\/v2\/tags\/361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/18kenglish.com\/th\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/18kenglish.com\/th\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/18kenglish.com\/th\/wp-json\/wp\/v2\/posts?tags=361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}