{"id":839,"count":2,"description":"","link":"https:\/\/18kenglish.com\/th\/tag\/\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19-2\/","name":"\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19","slug":"everyday-life","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/18kenglish.com\/th\/wp-json\/wp\/v2\/tags\/839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/18kenglish.com\/th\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/18kenglish.com\/th\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/18kenglish.com\/th\/wp-json\/wp\/v2\/posts?tags=839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}