{"id":841,"count":4,"description":"","link":"https:\/\/18kenglish.com\/th\/tag\/free-pdf-worksheet\/","name":"\u0e41\u0e1a\u0e1a\u0e1d\u0e36\u0e01\u0e2b\u0e31\u0e14 PDF \u0e1f\u0e23\u0e35","slug":"free-pdf-worksheet","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/18kenglish.com\/th\/wp-json\/wp\/v2\/tags\/841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/18kenglish.com\/th\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/18kenglish.com\/th\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/18kenglish.com\/th\/wp-json\/wp\/v2\/posts?tags=841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}